{"id":29947,"date":"2026-07-15T15:27:36","date_gmt":"2026-07-15T08:27:36","guid":{"rendered":"https:\/\/profender4x4.com\/?p=29947"},"modified":"2026-07-15T15:27:43","modified_gmt":"2026-07-15T08:27:43","slug":"%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa","status":"publish","type":"post","link":"https:\/\/profender4x4.com\/en\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/","title":{"rendered":"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29947\" class=\"elementor elementor-29947\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6697fb8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6697fb8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-210f47ba\" data-id=\"210f47ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c94163b elementor-widget elementor-widget-text-editor\" data-id=\"2c94163b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\n\n<article class=\"profender-post\">\n\n  \n  <h1>Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e23\u0e16\u0e04\u0e38\u0e13<\/h1>\n\n  \n  <p><strong>Profender Type 4<\/strong> (\u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e44\u0e17\u0e1b\u0e4c\u0e42\u0e1f\u0e23\u0e4c) \u0e04\u0e37\u0e2d\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e\u0e2b\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e22\u0e01\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e16\u0e36\u0e07 4 \u0e08\u0e38\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e22\u0e37\u0e14 (Rebound) \u0e41\u0e25\u0e30\u0e22\u0e38\u0e1a (Compression) \u0e41\u0e1a\u0e1a\u0e41\u0e22\u0e01 High\/Low Speed \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e31\u0e07\u0e1e\u0e31\u0e01\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e22\u0e01 (Sub-tank) \u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e04\u0e23\u0e35\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e41\u0e15\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e01\u0e39\u0e4a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 Honda Giorno, Yamaha XMAX \u0e41\u0e25\u0e30 Honda Forza 350 \u0e42\u0e14\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a Monotube \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 <a href=\"REPLACE-WITH-INTERNAL-URL\">\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Monotube \u0e01\u0e31\u0e1a Twintube \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/a><\/p>\n\n  \n  <figure style=\"text-align:center; margin:1.5em auto;\">\n    <img decoding=\"async\" src=\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/Type4-Giorno_-01.webp\"\n         alt=\"\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e15\u0e47\u0e21\u0e15\u0e31\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\"\n         width=\"1200\" style=\"display:block; margin:0 auto; max-width:100%; height:auto;\" \/>\n    <figcaption style=\"text-align:center;\">\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e14\u0e38\u0e14\u0e31\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e41\u0e15\u0e48\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32<\/figcaption>\n  <\/figure>\n\n  \n  <h2>\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 Profender Type 4 \u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e42\u0e0a\u0e4a\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b<\/h2>\n  <ul>\n    <li><strong>\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21<\/strong> \u2014 \u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e41\u0e15\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e17\u0e19\u0e17\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28<\/li>\n    <li><strong>\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e04\u0e39\u0e13\u0e2a\u0e2d\u0e07 (X2)<\/strong> \u2014 \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c (Sub-tank) \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e23\u0e35\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e43\u0e19\u0e42\u0e0a\u0e4a\u0e04\u0e43\u0e2b\u0e49\u0e04\u0e07\u0e17\u0e35\u0e48 \u0e02\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e31\u0e07\u0e27\u0e25<\/li>\n    <li><strong>\u0e0b\u0e35\u0e25\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 2 \u0e0a\u0e31\u0e49\u0e19<\/strong> \u2014 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e23\u0e31\u0e48\u0e27\u0e0b\u0e36\u0e21 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e41\u0e25\u0e30\u0e02\u0e23\u0e38\u0e02\u0e23\u0e30<\/li>\n  <\/ul>\n\n  \n  <h2>\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e0b\u0e47\u0e15 4 \u0e08\u0e38\u0e14\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e42\u0e0a\u0e4a\u0e04\u0e15\u0e31\u0e27\u0e19\u0e35\u0e49<\/h2>\n\n  \n  <figure style=\"text-align:center; margin:1.5em auto;\">\n    <img decoding=\"async\" src=\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/Type4-Forza350-03.webp\"\n         alt=\"\u0e1b\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e31\u0e1a High Speed \u0e41\u0e25\u0e30 Low Speed \u0e02\u0e2d\u0e07\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e41\u0e22\u0e01\u0e2a\u0e35\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\"\n         width=\"1200\" style=\"display:block; margin:0 auto; max-width:100%; height:auto;\" \/>\n    <figcaption style=\"text-align:center;\">\u0e1b\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e22\u0e01\u0e2a\u0e35\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e04\u0e38\u0e21\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e22\u0e37\u0e14\u0e41\u0e25\u0e30\u0e22\u0e38\u0e1a<\/figcaption>\n  <\/figure>\n\n  <p>\u0e42\u0e0a\u0e4a\u0e04\u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1b\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e22\u0e01\u0e2a\u0e35\u0e44\u0e27\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e1a\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19 2 \u0e1d\u0e31\u0e48\u0e07 \u0e04\u0e37\u0e2d Rebound (\u0e01\u0e32\u0e23\u0e14\u0e35\u0e14\u0e01\u0e25\u0e31\u0e1a) \u0e41\u0e25\u0e30 Compression (\u0e02\u0e32\u0e22\u0e38\u0e1a) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e1f\u0e35\u0e25\u0e25\u0e34\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14:<\/p>\n  <p><strong>\u0e1d\u0e31\u0e48\u0e07 Rebound (\u0e01\u0e32\u0e23\u0e14\u0e35\u0e14\u0e01\u0e25\u0e31\u0e1a)<\/strong><\/p>\n  <ul>\n    <li><strong>\u0e1b\u0e38\u0e48\u0e21\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19<\/strong> \u2014 \u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19 High Speed \u0e08\u0e33\u0e19\u0e27\u0e19 3 \u0e23\u0e30\u0e14\u0e31\u0e1a<\/li>\n    <li><strong>\u0e1b\u0e38\u0e48\u0e21\u0e2a\u0e35\u0e14\u0e33<\/strong> \u2014 \u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19 Low Speed \u0e08\u0e33\u0e19\u0e27\u0e19 16 \u0e23\u0e30\u0e14\u0e31\u0e1a<\/li>\n  <\/ul>\n  <p><strong>\u0e1d\u0e31\u0e48\u0e07 Compression (\u0e02\u0e32\u0e22\u0e38\u0e1a)<\/strong><\/p>\n  <ul>\n    <li><strong>\u0e1b\u0e38\u0e48\u0e21\u0e2a\u0e35\u0e41\u0e14\u0e07<\/strong> \u2014 \u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19 High Speed \u0e08\u0e33\u0e19\u0e27\u0e19 3 \u0e23\u0e30\u0e14\u0e31\u0e1a<\/li>\n    <li><strong>\u0e1b\u0e38\u0e48\u0e21\u0e2a\u0e35\u0e14\u0e33<\/strong> \u2014 \u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19 Low Speed \u0e08\u0e33\u0e19\u0e27\u0e19 16 \u0e23\u0e30\u0e14\u0e31\u0e1a<\/li>\n  <\/ul>\n  <ul>\n    <li><strong>Lock Nut<\/strong> \u2014 \u0e1b\u0e23\u0e31\u0e1a Preload Spring \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e2b\u0e39\u0e42\u0e0a\u0e4a\u0e04\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 (\u0e22\u0e01\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49 10-15 mm. \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e23\u0e16)<\/li>\n  <\/ul>\n\n  \n  <h2>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e35\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 8 \u0e2a\u0e35 \u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e0b\u0e49\u0e33\u0e43\u0e04\u0e23<\/h2>\n  <p>\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e35\u0e1b\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e27\u0e19\u0e25\u0e47\u0e2d\u0e04\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 8 \u0e2a\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e07\u0e34\u0e19 \u0e21\u0e48\u0e27\u0e07 \u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19 \u0e40\u0e02\u0e35\u0e22\u0e27 \u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2a\u0e49\u0e21 \u0e0a\u0e21\u0e1e\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e14\u0e07 \u0e41\u0e21\u0e17\u0e0a\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e2a\u0e35\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e07\u0e15\u0e31\u0e27<\/p>\n\n  \n  <h2>Profender Type 4 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e43\u0e04\u0e23<\/h2>\n  <p>\u0e42\u0e0a\u0e4a\u0e04\u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e2a\u0e01\u0e39\u0e4a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07\u0e40\u0e14\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e14\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e22\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e19\u0e38\u0e48\u0e21\u0e0b\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e08\u0e2d\u0e16\u0e19\u0e19\u0e02\u0e23\u0e38\u0e02\u0e23\u0e30 \u0e2a\u0e32\u0e22\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e41\u0e25\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e04\u0e19\u0e0b\u0e49\u0e2d\u0e19 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e22\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e36\u0e1a\u0e41\u0e19\u0e48\u0e19\u0e43\u0e19\u0e17\u0e32\u0e07\u0e42\u0e04\u0e49\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49 \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e08\u0e36\u0e07\u0e08\u0e39\u0e19\u0e04\u0e32\u0e41\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e47\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e42\u0e0a\u0e4a\u0e04 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/p>\n\n  \n  <h2>\u0e23\u0e38\u0e48\u0e19\u0e23\u0e16\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32 Profender Type 4<\/h2>\n  <table>\n    <thead>\n      <tr>\n        <th>\u0e23\u0e38\u0e48\u0e19\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c<\/th>\n        <th>\u0e2a\u0e40\u0e1b\u0e04 (\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27)<\/th>\n        <th>\u0e23\u0e32\u0e04\u0e32<\/th>\n      <\/tr>\n    <\/thead>\n    <tbody>\n      <tr>\n        <td>Yamaha XMAX 250\/300<\/td>\n        <td>LOAD-STD-LIFT (345-350-355 \u0e21\u0e21.)<\/td>\n        <td>28,500 \u0e1a\u0e32\u0e17 (\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 22,800 \u0e1a\u0e32\u0e17)<\/td>\n      <\/tr>\n      <tr>\n        <td>Honda Forza 350 (STD-LIFT)<\/td>\n        <td>430-445 \u0e21\u0e21.<\/td>\n        <td>28,000 \u0e1a\u0e32\u0e17<\/td>\n      <\/tr>\n      <tr>\n        <td>Honda Forza 350 (LOAD)<\/td>\n        <td>400-385 \u0e21\u0e21.<\/td>\n        <td>28,000 \u0e1a\u0e32\u0e17<\/td>\n      <\/tr>\n      <tr>\n        <td>Honda Giorno+<\/td>\n        <td>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/td>\n        <td>12,800 \u0e1a\u0e32\u0e17<\/td>\n      <\/tr>\n    <\/tbody>\n  <\/table>\n\n  \n  <h2>\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 Profender Type 4<\/h2>\n\n  <h3>Profender Type 4 \u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07<\/h3>\n  <p>\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e1d\u0e31\u0e48\u0e07 Rebound (\u0e01\u0e32\u0e23\u0e14\u0e35\u0e14\u0e01\u0e25\u0e31\u0e1a) \u0e41\u0e25\u0e30 Compression (\u0e02\u0e32\u0e22\u0e38\u0e1a) \u0e42\u0e14\u0e22\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1d\u0e31\u0e48\u0e07\u0e41\u0e22\u0e01\u0e1b\u0e23\u0e31\u0e1a High Speed 3 \u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30 Low Speed 16 \u0e23\u0e30\u0e14\u0e31\u0e1a (\u0e2b\u0e21\u0e38\u0e19\u0e19\u0e31\u0e1a\u0e04\u0e25\u0e34\u0e01) \u0e1e\u0e23\u0e49\u0e2d\u0e21 Lock Nut \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e31\u0e1a Preload \u0e2a\u0e1b\u0e23\u0e34\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e39\u0e42\u0e0a\u0e4a\u0e04\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19<\/p>\n\n  <h3>High Speed \u0e01\u0e31\u0e1a Low Speed \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/h3>\n  <p>High-Speed Compression \u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e40\u0e23\u0e47\u0e27 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e01\u0e2b\u0e25\u0e38\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01\u0e25\u0e39\u0e01\u0e23\u0e30\u0e19\u0e32\u0e14 \u0e2a\u0e48\u0e27\u0e19 Low-Speed Compression \u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e0a\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e42\u0e04\u0e49\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e41\u0e22\u0e01\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e34\u0e2a\u0e23\u0e30<\/p>\n\n  <h3>\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e44\u0e2b\u0e21<\/h3>\n  <p>\u0e44\u0e14\u0e49 \u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e2b\u0e39\u0e42\u0e0a\u0e4a\u0e04\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e22\u0e01\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 10\u201315 \u0e21\u0e21. \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e23\u0e16 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e1b\u0e23\u0e34\u0e07<\/p>\n\n  <h3>Profender Type 4 \u0e43\u0e2a\u0e48\u0e23\u0e16\u0e23\u0e38\u0e48\u0e19\u0e44\u0e2b\u0e19\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48<\/h3>\n  <p>\u0e21\u0e35\u0e2a\u0e40\u0e1b\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Yamaha XMAX 250\/300 (\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 22,800 \u0e1a\u0e32\u0e17), Honda Forza 350 (28,000 \u0e1a\u0e32\u0e17), Honda Giorno+ (12,800 \u0e1a\u0e32\u0e17) \u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e2a\u0e40\u0e1b\u0e01\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e17\u0e35\u0e48\u0e15\u0e23\u0e07\u0e23\u0e38\u0e48\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49<\/p>\n\n  \n  <h2>\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d Profender Type 4<\/h2>\n  <p>\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 Profender \u0e22\u0e34\u0e19\u0e14\u0e35\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e40\u0e1b\u0e01\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e15\u0e2d\u0e31\u0e1e\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n  <p><strong>\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21:<\/strong><\/p>\n  <ul>\n    <li>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 Profender (Dealer) \u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/li>\n    <li>Facebook Page: <a href=\"https:\/\/www.facebook.com\/Profendershox\" target=\"_blank\" rel=\"noopener\" style=\"color:#d32f2f;\">Profendershox<\/a><\/li>\n    <li>LINE Official: <a href=\"https:\/\/line.me\/R\/ti\/p\/@profender\" target=\"_blank\" rel=\"noopener\" style=\"color:#d32f2f;\">@profender<\/a><\/li>\n    <li>\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c: <a href=\"tel:0955509837\" style=\"color:#d32f2f;\">095-550-9837<\/a> \u0e2b\u0e23\u0e37\u0e2d <a href=\"tel:0657154942\" style=\"color:#d32f2f;\">065-715-4942<\/a><\/li>\n  <\/ul>\n\n<\/article>\n\n\n<!-- ================================================================\n     FAQ SCHEMA (JSON-LD) \u2014 \u0e27\u0e32\u0e07\u0e43\u0e19 <head> \u0e2b\u0e23\u0e37\u0e2d Elementor Custom Code\n     ================================================================ -->\n<script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [\n    {\n      \"@type\": \"Question\",\n      \"name\": \"Profender Type 4 \u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e1d\u0e31\u0e48\u0e07 Rebound (\u0e01\u0e32\u0e23\u0e14\u0e35\u0e14\u0e01\u0e25\u0e31\u0e1a) \u0e41\u0e25\u0e30 Compression (\u0e02\u0e32\u0e22\u0e38\u0e1a) \u0e42\u0e14\u0e22\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1d\u0e31\u0e48\u0e07\u0e41\u0e22\u0e01\u0e1b\u0e23\u0e31\u0e1a High Speed 3 \u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30 Low Speed 16 \u0e23\u0e30\u0e14\u0e31\u0e1a \u0e1e\u0e23\u0e49\u0e2d\u0e21 Lock Nut \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e31\u0e1a Preload \u0e2a\u0e1b\u0e23\u0e34\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e39\u0e42\u0e0a\u0e4a\u0e04\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"High Speed \u0e01\u0e31\u0e1a Low Speed \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"High-Speed Compression \u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e40\u0e23\u0e47\u0e27 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e01\u0e2b\u0e25\u0e38\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01\u0e25\u0e39\u0e01\u0e23\u0e30\u0e19\u0e32\u0e14 \u0e2a\u0e48\u0e27\u0e19 Low-Speed Compression \u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e0a\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e42\u0e04\u0e49\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e41\u0e22\u0e01\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e34\u0e2a\u0e23\u0e30\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e44\u0e2b\u0e21\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"\u0e44\u0e14\u0e49 \u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e2b\u0e39\u0e42\u0e0a\u0e4a\u0e04\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e22\u0e01\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 10 \u0e16\u0e36\u0e07 15 \u0e21\u0e21. \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e23\u0e16 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e1b\u0e23\u0e34\u0e07\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"Profender Type 4 \u0e43\u0e2a\u0e48\u0e23\u0e16\u0e23\u0e38\u0e48\u0e19\u0e44\u0e2b\u0e19\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"\u0e21\u0e35\u0e2a\u0e40\u0e1b\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Yamaha XMAX 250\/300 (\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 22,800 \u0e1a\u0e32\u0e17), Honda Forza 350 (28,000 \u0e1a\u0e32\u0e17), Honda Giorno+ (12,800 \u0e1a\u0e32\u0e17) \u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e2a\u0e40\u0e1b\u0e01\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e17\u0e35\u0e48\u0e15\u0e23\u0e07\u0e23\u0e38\u0e48\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\"\n      }\n    }\n  ]\n}\n<\/script>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e23\u0e16\u0e04\u0e38\u0e13 Profender Type 4 (\u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e44\u0e17\u0e1b\u0e4c\u0e42\u0e1f\u0e23\u0e4c) \u0e04\u0e37\u0e2d\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e\u0e2b\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e22\u0e01\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e16\u0e36\u0e07 4 \u0e08\u0e38\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e22\u0e37\u0e14 (Rebound) \u0e41\u0e25\u0e30\u0e22\u0e38\u0e1a (Compression) \u0e41\u0e1a\u0e1a\u0e41\u0e22\u0e01 High\/Low Speed \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e31\u0e07\u0e1e\u0e31\u0e01\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e22\u0e01 (Sub-tank) \u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e04\u0e23\u0e35\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e41\u0e15\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e01\u0e39\u0e4a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 Honda Giorno, Yamaha XMAX \u0e41\u0e25\u0e30 Honda Forza 350 \u0e42\u0e14\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a Monotube \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Monotube \u0e01\u0e31\u0e1a Twintube \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e14\u0e38\u0e14\u0e31\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e41\u0e15\u0e48\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49 Profender Type 4 \u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e42\u0e0a\u0e4a\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b&#8230;<\/p>\n","protected":false},"author":5,"featured_media":29957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-29947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v22.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 | \u0e23\u0e32\u0e04\u0e32\u0e42\u0e1b\u0e23\u0e2f XMAX Forza<\/title>\n<meta name=\"description\" content=\"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 Rebound\/High\/Low Speed \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01 8 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350, Giorno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/profender4x4.com\/\u0e23\u0e27\u0e27-\u0e42\u0e0a\u0e04\u0e2d\u0e1e-profender-type-4-\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e08\u0e32\u0e01\u0e2a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno\" \/>\n<meta property=\"og:description\" content=\"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 Rebound\/High\/Low Speed \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01 8 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350, Giorno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/profender4x4.com\/\u0e23\u0e27\u0e27-\u0e42\u0e0a\u0e04\u0e2d\u0e1e-profender-type-4-\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e08\u0e32\u0e01\u0e2a\/\" \/>\n<meta property=\"og:site_name\" content=\"Profender4x4\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T08:27:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T08:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2528\" \/>\n\t<meta property=\"og:image:height\" content=\"1686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Profender Official\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Profender Official\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/\"},\"author\":{\"name\":\"Profender Official\",\"@id\":\"https:\/\/profender4x4.com\/#\/schema\/person\/6dae2c2b3c93db7540dd127a30413a1b\"},\"headline\":\"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno\",\"datePublished\":\"2026-07-15T08:27:36+00:00\",\"dateModified\":\"2026-07-15T08:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/\"},\"wordCount\":109,\"publisher\":{\"@id\":\"https:\/\/profender4x4.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp\",\"articleSection\":[\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/\",\"url\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/\",\"name\":\"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 | \u0e23\u0e32\u0e04\u0e32\u0e42\u0e1b\u0e23\u0e2f XMAX Forza\",\"isPartOf\":{\"@id\":\"https:\/\/profender4x4.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp\",\"datePublished\":\"2026-07-15T08:27:36+00:00\",\"dateModified\":\"2026-07-15T08:27:43+00:00\",\"description\":\"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 Rebound\/High\/Low Speed \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01 8 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350, Giorno\",\"breadcrumb\":{\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage\",\"url\":\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp\",\"contentUrl\":\"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp\",\"width\":2528,\"height\":1686,\"caption\":\"\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e15\u0e47\u0e21\u0e15\u0e31\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/profender4x4.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/profender4x4.com\/#website\",\"url\":\"https:\/\/profender4x4.com\/\",\"name\":\"Profender4x4\",\"description\":\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e0a\u0e49\u0e04\u0e2d\u0e31\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\",\"publisher\":{\"@id\":\"https:\/\/profender4x4.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/profender4x4.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/profender4x4.com\/#organization\",\"name\":\"Profender4x4\",\"alternateName\":\"WELCOME TO PROFENDER 4X4\",\"url\":\"https:\/\/profender4x4.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/profender4x4.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/profender4x4.com\/wp-content\/uploads\/2022\/03\/10644845_790452124340533_1309020975163812285_n-removebg-preview.png\",\"contentUrl\":\"https:\/\/profender4x4.com\/wp-content\/uploads\/2022\/03\/10644845_790452124340533_1309020975163812285_n-removebg-preview.png\",\"width\":500,\"height\":500,\"caption\":\"Profender4x4\"},\"image\":{\"@id\":\"https:\/\/profender4x4.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/profender4x4.com\/#\/schema\/person\/6dae2c2b3c93db7540dd127a30413a1b\",\"name\":\"Profender Official\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 | \u0e23\u0e32\u0e04\u0e32\u0e42\u0e1b\u0e23\u0e2f XMAX Forza","description":"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 Rebound\/High\/Low Speed \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01 8 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350, Giorno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/profender4x4.com\/\u0e23\u0e27\u0e27-\u0e42\u0e0a\u0e04\u0e2d\u0e1e-profender-type-4-\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e08\u0e32\u0e01\u0e2a\/","og_locale":"en_US","og_type":"article","og_title":"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno","og_description":"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 Rebound\/High\/Low Speed \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01 8 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350, Giorno","og_url":"https:\/\/profender4x4.com\/\u0e23\u0e27\u0e27-\u0e42\u0e0a\u0e04\u0e2d\u0e1e-profender-type-4-\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e08\u0e32\u0e01\u0e2a\/","og_site_name":"Profender4x4","article_published_time":"2026-07-15T08:27:36+00:00","article_modified_time":"2026-07-15T08:27:43+00:00","og_image":[{"width":2528,"height":1686,"url":"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp","type":"image\/webp"}],"author":"Profender Official","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Profender Official","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#article","isPartOf":{"@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/"},"author":{"name":"Profender Official","@id":"https:\/\/profender4x4.com\/#\/schema\/person\/6dae2c2b3c93db7540dd127a30413a1b"},"headline":"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno","datePublished":"2026-07-15T08:27:36+00:00","dateModified":"2026-07-15T08:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/"},"wordCount":109,"publisher":{"@id":"https:\/\/profender4x4.com\/#organization"},"image":{"@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp","articleSection":["\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/","url":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/","name":"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 | \u0e23\u0e32\u0e04\u0e32\u0e42\u0e1b\u0e23\u0e2f XMAX Forza","isPartOf":{"@id":"https:\/\/profender4x4.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage"},"image":{"@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp","datePublished":"2026-07-15T08:27:36+00:00","dateModified":"2026-07-15T08:27:43+00:00","description":"Profender Type 4 \u0e42\u0e0a\u0e4a\u0e04\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e31\u0e1a 4 \u0e08\u0e38\u0e14 Rebound\/High\/Low Speed \u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01 8 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350, Giorno","breadcrumb":{"@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#primaryimage","url":"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp","contentUrl":"https:\/\/profender4x4.com\/wp-content\/uploads\/2026\/07\/type4.webp","width":2528,"height":1686,"caption":"\u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e15\u0e47\u0e21\u0e15\u0e31\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e23\u0e14\u0e2a\u0e39\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e31\u0e07\u0e0b\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19"},{"@type":"BreadcrumbList","@id":"https:\/\/profender4x4.com\/%e0%b8%a3%e0%b8%a7%e0%b8%a7-%e0%b9%82%e0%b8%8a%e0%b8%84%e0%b8%ad%e0%b8%9e-profender-type-4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/profender4x4.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e42\u0e0a\u0e4a\u0e04\u0e2d\u0e31\u0e1e Profender Type 4 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e02\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a XMAX, Forza 350 \u0e41\u0e25\u0e30 Giorno"}]},{"@type":"WebSite","@id":"https:\/\/profender4x4.com\/#website","url":"https:\/\/profender4x4.com\/","name":"Profender4x4","description":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e0a\u0e49\u0e04\u0e2d\u0e31\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49","publisher":{"@id":"https:\/\/profender4x4.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/profender4x4.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/profender4x4.com\/#organization","name":"Profender4x4","alternateName":"WELCOME TO PROFENDER 4X4","url":"https:\/\/profender4x4.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/profender4x4.com\/#\/schema\/logo\/image\/","url":"https:\/\/profender4x4.com\/wp-content\/uploads\/2022\/03\/10644845_790452124340533_1309020975163812285_n-removebg-preview.png","contentUrl":"https:\/\/profender4x4.com\/wp-content\/uploads\/2022\/03\/10644845_790452124340533_1309020975163812285_n-removebg-preview.png","width":500,"height":500,"caption":"Profender4x4"},"image":{"@id":"https:\/\/profender4x4.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/profender4x4.com\/#\/schema\/person\/6dae2c2b3c93db7540dd127a30413a1b","name":"Profender Official"}]}},"_links":{"self":[{"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/posts\/29947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/comments?post=29947"}],"version-history":[{"count":12,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/posts\/29947\/revisions"}],"predecessor-version":[{"id":29965,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/posts\/29947\/revisions\/29965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/media\/29957"}],"wp:attachment":[{"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/media?parent=29947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/categories?post=29947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/profender4x4.com\/en\/wp-json\/wp\/v2\/tags?post=29947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}